{"id":1216,"date":"2015-09-23T18:10:49","date_gmt":"2015-09-23T18:10:49","guid":{"rendered":"http:\/\/www.correspondentevianopolino.com.br\/?p=1216"},"modified":"2015-09-23T18:10:49","modified_gmt":"2015-09-23T18:10:49","slug":"fossa-desativada-desaba-e-pessoas-caem-dentro-da-mesma-na-noite-de-ontem-no-parque-agropecuario__trashed","status":"publish","type":"post","link":"https:\/\/www.correspondentevianopolino.com.br\/site\/fossa-desativada-desaba-e-pessoas-caem-dentro-da-mesma-na-noite-de-ontem-no-parque-agropecuario__trashed\/","title":{"rendered":"Fossa desativada desaba e pessoas caem dentro da mesma na noite de ontem no Parque Agropecu?rio"},"content":{"rendered":"<p>Uma fossa desativada e sobre a qual estavam alguns banheiros qu?micos desabou ontem, 15, quando acontecia um dos shows musicais no Parque Agropecu?rio de Vian?polis.<br \/>\nCom o desabamento, algumas pessoas ca?ram no buraco e tiveram ferimentos.<br \/>\nLogo depois, alguns populares, revoltados com o ocorrido, chutaram os banheiros e jogaram diversos deles no ch?o.<br \/>\nO prefeito Issy Quinan J?nior lamentou o ocorrido e pediu desculpas ?s pessoas que, infelizmente, foram vitimas deste acidente. Ele disse que estar? pessoalmente empenhado em reparar o transtorno e danos causados ?s pessoas.<br \/>\nO prefeito vianopolino finalizou dizendo que j? determinou a apura??o do ocorrido, para se verificar se houve falha por parte da organiza??o e do setor respons?vel, no atendimento e socorro ?s v?timas do acidente ocorrido na noite de ontem no Parque Agropecu?rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma fossa desativada e sobre a qual estavam alguns banheiros qu?micos desabou ontem, 15, quando acontecia um dos shows musicais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[],"class_list":["post-1216","post","type-post","status-publish","format-standard","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin@admin.com","author_link":"https:\/\/www.correspondentevianopolino.com.br\/site\/author\/adminadmin-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Uma fossa desativada e sobre a qual estavam alguns banheiros qu?micos desabou ontem, 15, quando acontecia um dos shows musicais [&hellip;]","_links":{"self":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/1216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/comments?post=1216"}],"version-history":[{"count":0,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/1216\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/media?parent=1216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/categories?post=1216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/tags?post=1216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}