{"id":369,"date":"2015-09-14T19:02:34","date_gmt":"2015-09-14T19:02:34","guid":{"rendered":"http:\/\/www.correspondentevianopolino.com.br\/?p=369"},"modified":"2015-09-14T19:02:34","modified_gmt":"2015-09-14T19:02:34","slug":"representantes-dos-poderes-executivo-judiciario-e-legislativo-vao-a-goiania-reivindicar-mais-seguranca-para-os-vianopolinos__trashed","status":"publish","type":"post","link":"https:\/\/www.correspondentevianopolino.com.br\/site\/representantes-dos-poderes-executivo-judiciario-e-legislativo-vao-a-goiania-reivindicar-mais-seguranca-para-os-vianopolinos__trashed\/","title":{"rendered":"Representantes dos Poderes Executivo, Judici?rio e Legislativo v?o a Goi?nia reivindicar mais seguran?a para os vianopolinos"},"content":{"rendered":"<p>O prefeito Issy Quinan J?nior, a ju?za de Vian?polis, Marli de F?tima Naves, o presidente da C?mara Municipal, Cleydson Mascarenhas, e representantes do Conselho da Comunidade na Execu??o Penal ser?o recebidos em Goi?nia, na manh? da pr?xima sexta-feira, 04, pelo Secret?rio de Seguran?a P?blica de Goi?s, Joaquim Mesquita.<br \/>\nNa audi?ncia, solicitada pelo Poder Judici?rio, as autoridades constitu?das de nosso munic?pio v?o levar ao conhecimento do Secret?rio Joaquim Mesquita os problemas da falta de seguran?a enfrentados pela popula??o.<br \/>\nDiante dos clamores dos moradores de Vian?polis, assim como de Ponte Funda e Cara?ba, que reivindicam a??es mais contundentes no combate ? criminalidade, as autoridades constitu?das do nosso munic?pio apresentar?o ao Secret?rio uma s?rie de reivindica??es.<br \/>\nUltimamente, al?m das explos?es de caixas eletr?nicos em duas ag?ncias banc?rias, assaltos a resid?ncias, furtos e outros tipos de a??es criminosas foram registrados em Vian?polis e tamb?m na localidade de Ponte Funda.<br \/>\nNaquela localidade, de acordo com um morador, a popula??o est? com medo e assustada, uma vez que as ocorr?ncias policiais aumentaram consideravelmente e o combate ? criminalidade deixa a desejar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Issy Quinan J?nior, a ju?za de Vian?polis, Marli de F?tima Naves, o presidente da C?mara Municipal, Cleydson Mascarenhas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin@admin.com","author_link":"https:\/\/www.correspondentevianopolino.com.br\/site\/author\/adminadmin-com\/"},"uagb_comment_info":0,"uagb_excerpt":"O prefeito Issy Quinan J?nior, a ju?za de Vian?polis, Marli de F?tima Naves, o presidente da C?mara Municipal, Cleydson Mascarenhas, [&hellip;]","_links":{"self":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":0,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}