{"id":74939,"date":"2022-04-11T06:09:52","date_gmt":"2022-04-11T09:09:52","guid":{"rendered":"https:\/\/www.correspondentevianopolino.com.br\/site\/?p=74939"},"modified":"2022-04-11T09:33:44","modified_gmt":"2022-04-11T12:33:44","slug":"triste-realidade-grande-maioria-dos-vianopolinos-nao-colabora-com-o-combate-a-dengue","status":"publish","type":"post","link":"https:\/\/www.correspondentevianopolino.com.br\/site\/triste-realidade-grande-maioria-dos-vianopolinos-nao-colabora-com-o-combate-a-dengue\/","title":{"rendered":"Servidor da Secretaria de Sa\u00fade \u00e9 taxativo e diz que GRANDE MAIORIA dos vianopolinos n\u00e3o colabora com o combate \u00e0 dengue"},"content":{"rendered":"\n<p>Uma triste realidade: a grande maioria dos moradores de Vian\u00f3polis n\u00e3o colabora, como precisa, para combater a dengue.<\/p>\n\n\n\n<p>Ap\u00f3s o aumento de casos de dengue em nosso munic\u00edpio, nossa reportagem foi atr\u00e1s de informa\u00e7\u00f5es, buscando realizar uma mat\u00e9ria de alerta sobre essa doen\u00e7a.<\/p>\n\n\n\n<p>Vian\u00f3polis est\u00e1 entre as 127 cidades de Goi\u00e1s com alto risco de ocorr\u00eancia da dengue.<\/p>\n\n\n\n<p>Dessa maneira, a preocupa\u00e7\u00e3o aumenta e os agentes de combate \u00e0s endemias, infelizmente, enfrentam dificuldades no trabalho de combate ao mosquito Aedes Aegypti.<\/p>\n\n\n\n<p>E, a dengue mata. <strong>Ali\u00e1s, Goi\u00e1s \u00e9 o 2\u00ba Estado do pa\u00eds em mortes por dengue.<\/strong><\/p>\n\n\n\n<p>Documento da Secretaria de Estado da Sa\u00fade enviado aos munic\u00edpios de Goi\u00e1s diz que a r\u00e1pida expans\u00e3o do n\u00famero de casos de dengue e chikungunya neste ano desperta preocupa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ao conversar com alguns servidores que atuam no combate \u00e0 dengue em nosso munic\u00edpio, descobrimos que grande parte da popula\u00e7\u00e3o n\u00e3o d\u00e1 a necess\u00e1ria colabora\u00e7\u00e3o na luta contra a dengue.<\/p>\n\n\n\n<p><strong>Um dos servidores falou \u00e0 nossa reportagem na condi\u00e7\u00e3o de que seu nome n\u00e3o fosse divulgado e nos relatou algumas das dificuldades encontradas no contato com moradores.<\/strong><\/p>\n\n\n\n<p>Em um dos casos, ao constatar larvas do mosquito Aedes Aegypti em uma resid\u00eancia de nossa cidade, o agente de endemias disse que iria jogar fora a \u00e1gua que estava em um gal\u00e3o. A moradora n\u00e3o concordou com a decis\u00e3o do agente, pois iria usar a \u00e1gua para alguma finalidade e somente depois de muitos argumentos \u00e9 que a \u00e1gua foi descartada.<\/p>\n\n\n\n<p>Outros relatos d\u00e3o contam que moradores mostram ignor\u00e2ncia quanto aos cuidados dos im\u00f3veis fechados e de terrenos baldios. Os propriet\u00e1rios os deixam abandonados e o mato esconde poss\u00edveis criadouros do mosquito transmissor da dengue.<\/p>\n\n\n\n<p>Outro problema s\u00e9rio nos relatos que ouvimos, \u00e9 que muitos moradores vizinhos de terrenos baldios jogam lixo nos mesmos, piorando ainda mais a situa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Existem tamb\u00e9m reincid\u00eancias de problemas, mesmo ap\u00f3s orienta\u00e7\u00e3o quanto \u00e0s adequa\u00e7\u00f5es no combate \u00e0 dengue.<\/p>\n\n\n\n<p>E, por fim, existem casos de moradores que atendem de maneira truculenta os agentes de endemias, demonstrando ignor\u00e2ncia quanto aos perigos desta doen\u00e7a.<\/p>\n\n\n\n<p>Nos \u00faltimos dias, diversas pessoas de Vian\u00f3polis contra\u00edram dengue.<\/p>\n\n\n\n<p><strong>Um recado importante para todos: Fa\u00e7a sua parte no combate \u00e0 dengue! N\u00e3o ignore essa doen\u00e7a, ela mata!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-576x1024.jpg\" alt=\"\" class=\"wp-image-74871\" srcset=\"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-576x1024.jpg 576w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-465x827.jpg 465w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-169x300.jpg 169w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-768x1365.jpg 768w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-174x310.jpg 174w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-120x213.jpg 120w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-115x204.jpg 115w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6-107x190.jpg 107w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/thumbnail-6.jpg 1080w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n<figure class=\"wp-block-post-featured-image\"><img decoding=\"async\" width=\"225\" height=\"203\" src=\"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg 225w, https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1-211x190.jpg 211w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Uma triste realidade: a grande maioria dos moradores de Vian\u00f3polis n\u00e3o colabora, como precisa, para combater a dengue. Ap\u00f3s o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":74940,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-74939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas"],"uagb_featured_image_src":{"full":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"thumbnail":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"medium":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"medium_large":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"large":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"1536x1536":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false],"2048x2048":["https:\/\/www.correspondentevianopolino.com.br\/site\/wp-content\/uploads\/2022\/04\/images-1.jpg",225,203,false]},"uagb_author_info":{"display_name":"Ol\u00edvio Lemos","author_link":"https:\/\/www.correspondentevianopolino.com.br\/site\/author\/olivio\/"},"uagb_comment_info":0,"uagb_excerpt":"Uma triste realidade: a grande maioria dos moradores de Vian\u00f3polis n\u00e3o colabora, como precisa, para combater a dengue. Ap\u00f3s o [&hellip;]","_links":{"self":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/74939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/comments?post=74939"}],"version-history":[{"count":0,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/posts\/74939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/media\/74940"}],"wp:attachment":[{"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/media?parent=74939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/categories?post=74939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.correspondentevianopolino.com.br\/site\/wp-json\/wp\/v2\/tags?post=74939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}